{"id":6774,"date":"2022-08-18T16:32:10","date_gmt":"2022-08-18T16:32:10","guid":{"rendered":"https:\/\/gerens.pe\/blog\/?p=6774"},"modified":"2022-08-26T17:31:11","modified_gmt":"2022-08-26T17:31:11","slug":"perumin-35-contara-con-una-cumbre-de-agua-cambio-climatico-y-mineria","status":"publish","type":"post","link":"https:\/\/gerens.pe\/blog\/perumin-35-contara-con-una-cumbre-de-agua-cambio-climatico-y-mineria\/","title":{"rendered":"PERUMIN 35 CONTAR\u00c1 CON UNA CUMBRE DE AGUA, CAMBIO CLIM\u00c1TICO Y MINER\u00cdA"},"content":{"rendered":"<p class=\"ql-align-justify\">Una de las principales novedades en PERUMIN es que esta trig\u00e9simo quinta edici\u00f3n contar\u00e1 con una Cumbre de Agua, Cambio Clim\u00e1tico y Miner\u00eda, con la que se busca repensar la industria extractiva y su impacto en el entorno, desde un enfoque participativo, sostenible y reproducible, a fin de extremar las medidas de protecci\u00f3n de los recursos naturales. Conversamos con Vinio Floris, doctor en Ingenier\u00eda Civil Ambiental e integrante del comit\u00e9 organizador de dicha cumbre, quien nos brind\u00f3 mayores luces sobre este encuentro.<\/p>\n<p class=\"ql-align-justify\"><strong>\u00bfC\u00f3mo surge la primera edici\u00f3n de la Cumbre de Agua, Cambio Clim\u00e1tico y Miner\u00eda en PERUMIN, y qu\u00e9 importancia adquiere en estos tiempos?<\/strong><\/p>\n<p class=\"ql-align-justify\">La discusi\u00f3n de agua y miner\u00eda ha existido en ediciones anteriores de PERUMIN. Aun cuando el cambio clim\u00e1tico tambi\u00e9n ha sido tratado en forma aislada, se decidi\u00f3 enlazar estos tres elementos que est\u00e1n muy ligados entre s\u00ed. Esto propiciar\u00e1 un debate m\u00e1s completo con soluciones sin\u00e9rgicas m\u00e1s integrales. Esta discusi\u00f3n es sumamente actual y es el momento oportuno para presentar ideas e iniciativas y discutir sus impactos en los a\u00f1os venideros.<\/p>\n<p class=\"ql-align-justify\"><strong>\u00bfC\u00f3mo se estructurar\u00e1 el desarrollo de este encuentro?<\/strong><\/p>\n<p class=\"ql-align-justify\">La Cumbre tiene dos grandes mesas de discusi\u00f3n. La primera presenta el contexto del cambio clim\u00e1tico y sus impactos en los recursos h\u00eddricos con \u00e9nfasis en la cadena del valor minero. La discusi\u00f3n se enfoca en cuatro temas centrales: miner\u00eda sustentable y gesti\u00f3n del recurso h\u00eddrico; tecnolog\u00edas de gesti\u00f3n del agua y sus retos en el corto y largo plazo; soluciones globales replicables; y financiamiento sustentable.<\/p>\n<p class=\"ql-align-justify\"><strong>\u00bfQu\u00e9 podremos encontrar en la segunda mesa de debate?<\/strong><\/p>\n<p class=\"ql-align-justify\">La segunda mesa de discusi\u00f3n presenta y discute experiencias de iniciativas de proyectos mineros, sus retos y oportunidades de replicabilidad en la gesti\u00f3n del recurso h\u00eddrico en la cadena del valor minero bajo el contexto de cambio clim\u00e1tico. La discusi\u00f3n se enfoca en cuatro iniciativas puntuales: participaci\u00f3n p\u00fablico-privada en la cuenca del rio Chili (Arequipa); el uso eficiente y monitoreo del recurso h\u00eddrico y el bosque de Huarmey en Antamina; el desarrollo sostenible del recurso h\u00eddrico y el desarrollo comunitario en Pataz; y el rol de la academia en la investigaci\u00f3n y educaci\u00f3n en la gesti\u00f3n del recurso h\u00eddrico en la cadena del valor minero bajo cambio clim\u00e1tico.<\/p>\n<p class=\"ql-align-justify\">Cada mesa tiene un presentador principal que dar\u00e1 el contexto de la discusi\u00f3n y cuatro panelistas\/expositores que presentar\u00e1n sus experiencias y puntos de vista siguiendo los lineamientos arriba listados.<\/p>\n<p class=\"ql-align-justify\">Adicionalmente, se ha previsto una participaci\u00f3n con el p\u00fablico asistente. Al final del evento se presentar\u00e1n las conclusiones de toda la discusi\u00f3n.<\/p>\n<p class=\"ql-align-justify\"><strong>\u00bfCon qu\u00e9 entidades, empresas y organizaciones se est\u00e1 conversando para su participaci\u00f3n? \u00bfSe piensa traer a alguna autoridad de renombre mundial?<\/strong><\/p>\n<p class=\"ql-align-justify\">Todos los participantes del evento son reconocidos profesionales internacionales y locales y representan organizaciones muy prestigiosas de organismos de desarrollo, sociedad civil y empresa privada.<\/p>\n<p class=\"ql-align-justify\"><strong>\u00bfEn este foro tambi\u00e9n se ofrecer\u00e1 espacio para la presentaci\u00f3n de proyectos comunales de gesti\u00f3n h\u00eddrica? \u00bfQui\u00e9nes podr\u00edan ser los posibles ponentes?<\/strong><\/p>\n<p class=\"ql-align-justify\">El desarrollo comunitario sustentable es el denominador com\u00fan de todo el evento. Sin embargo, la segunda mesa se enfoca enteramente en los detalles de proyectos locales con un predominante efecto comunal.<\/p>\n<p class=\"ql-align-justify\"><strong>\u00bfCu\u00e1les son los temas en espec\u00edfico que se debatir\u00e1n bajo el eje tem\u00e1tico de cambio clim\u00e1tico? \u00bfSe expondr\u00e1n estudios sobre su impacto en la miner\u00eda?<\/strong><\/p>\n<p class=\"ql-align-justify\">La presentaci\u00f3n del contexto de la primera mesa redonda contempla una revisi\u00f3n exhaustiva, actual y factual de informaci\u00f3n de estos tres elementos con diversos escenarios al a\u00f1o 2050. La segunda hereda esta informaci\u00f3n general y la adopta a nivel espec\u00edfico de proyectos mineros siguiendo el pensamiento de \u201cpensar globalmente, actuar localmente\u201d.<\/p>\n<p class=\"ql-align-justify\"><strong>\u00bfCu\u00e1nta agua consume el sector minero y de qu\u00e9 manera est\u00e1 velando por su correcto uso?<\/strong><\/p>\n<p class=\"ql-align-justify\">La miner\u00eda formal en general consume una m\u00ednima parte de la oferta disponible (alrededor del 1.5% en el Per\u00fa). Reciclaje y re\u00faso son actividades comunes y en muchas operaciones se tiene descarga cero. En oposici\u00f3n, la miner\u00eda ilegal contundentemente contamina los causes dejando escenarios de inusitados y duraderos impactos ambientales y a la salud comunitaria.<\/p>\n<p class=\"ql-align-justify\"><strong>\u00bfVetar el ejercicio de la miner\u00eda en cabeceras de cuenca es un desprop\u00f3sito o un asunto que requiere de mayor reflexi\u00f3n?, \u00bfPor qu\u00e9?<\/strong><\/p>\n<p class=\"ql-align-justify\">Cualquier actividad en una cuenca hidrogr\u00e1fica debe ser estudiada y autorizada bajo los preceptos universales del desarrollo sostenible. Estas operaciones deben seguir sus mandatos est\u00e9n o no en las llamadas cabeceras de cuencas. Poner reglas (l\u00e9ase leyes, reglamentos, etc.) basados en pensamientos no ligados a las ciencias naturales interfieren con ella y sus principios, y cometen una injusticia al impedir el desarrollo de los pueblos y en el combate del cambio clim\u00e1tico, en donde la miner\u00eda tiene el rol protag\u00f3nico de proveer los materiales para mitigar sus nefastos impactos.<\/p>\n<p class=\"ql-align-justify\"><strong>\u00bfContribuye la regulaci\u00f3n ambiental peruana a la r\u00e1pida viabilidad de los proyectos mineros o es perfectible? \u00bfQu\u00e9 cambios podr\u00edan adherirse?<\/strong><\/p>\n<p class=\"ql-align-justify\">La regulaci\u00f3n ambiental peruana ha avanzado notablemente en los \u00faltimos veinte a\u00f1os, pero tiene vac\u00edos que se pueden subsanar. Sin embargo, tiene una gran brecha en su implementaci\u00f3n. Existen retos con descargas de aguas no tratadas (especialmente de uso poblacional) con \u00edndices elevad\u00edsimos de contaminaci\u00f3n que atentan gravemente contra el ambiente y la salud de las comunidades. El Per\u00fa tiene la oportunidad de conciliar un plan estrat\u00e9gico, basado en la ciencia y con apoyo de sus cuatro estamentos (Estado, sociedad civil, academia y empresa privada) para dise\u00f1ar e implementar escenarios que permitan crear una regulaci\u00f3n equilibrada para gestionar el recurso h\u00eddrico en forma sustentable combatiendo el cambio clim\u00e1tico.<\/p>\n<p><strong><em>Este art\u00edculo ha sido publicado originalmente por el <a href=\"https:\/\/iimp.org.pe\/institucional\/noticias\/perumin-35-contara-con-una-cumbre-de-agua-cambio-climatico-y-mineria\"><u>Instituto de Ingenieros de Minas del Per\u00fa<\/u><\/a>\u00a0a partir de una entrevista al Dr. Vinio Floris, <span lang=\"ES\"><a href=\"https:\/\/cgama.gerens.pe\/\">Director del Centro de Gesti\u00f3n de Agua y Medio Ambiente de la Escuela de Posgrado G\u011aRENS<\/a><\/span>.<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una de las principales novedades en PERUMIN es que esta trig\u00e9simo quinta edici\u00f3n contar\u00e1 con una Cumbre de Agua, Cambio Clim\u00e1tico y&#8230;<\/p>\n","protected":false},"author":2,"featured_media":6777,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[724,2],"tags":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/gerens.pe\/blog\/wp-json\/wp\/v2\/posts\/6774"}],"collection":[{"href":"https:\/\/gerens.pe\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gerens.pe\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gerens.pe\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/gerens.pe\/blog\/wp-json\/wp\/v2\/comments?post=6774"}],"version-history":[{"count":2,"href":"https:\/\/gerens.pe\/blog\/wp-json\/wp\/v2\/posts\/6774\/revisions"}],"predecessor-version":[{"id":6778,"href":"https:\/\/gerens.pe\/blog\/wp-json\/wp\/v2\/posts\/6774\/revisions\/6778"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gerens.pe\/blog\/wp-json\/wp\/v2\/media\/6777"}],"wp:attachment":[{"href":"https:\/\/gerens.pe\/blog\/wp-json\/wp\/v2\/media?parent=6774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gerens.pe\/blog\/wp-json\/wp\/v2\/categories?post=6774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gerens.pe\/blog\/wp-json\/wp\/v2\/tags?post=6774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}