{"id":3012,"date":"2017-06-01T09:47:06","date_gmt":"2017-06-01T14:47:06","guid":{"rendered":"https:\/\/gerens.pe\/blog\/?p=3012"},"modified":"2017-06-01T09:47:06","modified_gmt":"2017-06-01T14:47:06","slug":"plan-para-cerrar-oportunidad-aprovechar","status":"publish","type":"post","link":"https:\/\/gerens.pe\/blog\/plan-para-cerrar-oportunidad-aprovechar\/","title":{"rendered":"Plan para cerrar, oportunidad para aprovechar"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-3014\" src=\"https:\/\/gerens.pe\/blog\/wp-content\/uploads\/2017\/05\/Plan-para-cerrar-oportunidad-para-aprovechar-1024x536.png\" alt=\"Plan-para-cerrar\" width=\"720\" height=\"377\" srcset=\"https:\/\/gerens.pe\/blog\/wp-content\/uploads\/2017\/05\/Plan-para-cerrar-oportunidad-para-aprovechar-1024x536.png 1024w, https:\/\/gerens.pe\/blog\/wp-content\/uploads\/2017\/05\/Plan-para-cerrar-oportunidad-para-aprovechar-300x157.png 300w, https:\/\/gerens.pe\/blog\/wp-content\/uploads\/2017\/05\/Plan-para-cerrar-oportunidad-para-aprovechar-768x402.png 768w, https:\/\/gerens.pe\/blog\/wp-content\/uploads\/2017\/05\/Plan-para-cerrar-oportunidad-para-aprovechar-360x188.png 360w, https:\/\/gerens.pe\/blog\/wp-content\/uploads\/2017\/05\/Plan-para-cerrar-oportunidad-para-aprovechar.png 1200w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/p>\n<p style=\"text-align: center;\"><strong>Innovador, atrevido, de alto impacto y de gran utilidad result\u00f3 la iniciativa de brindar a la \u201cacademia\u201d una oferta educativa diferente relacionada a los planes de cierre.<\/strong><\/p>\n<p style=\"text-align: justify;\">El pasado mayo del 2017 concluimos con mucho \u00e9xito el 1er Diplomado de Gesti\u00f3n Integral de Planes de Cierre \u2013 Sector Minero y Afines, una iniciativa y esfuerzo conjunto con la Escuela de Postgrado GERENS.<\/p>\n<p style=\"text-align: justify;\">Bajo el lema de \u201cno venimos a tomar conocimiento, sino venimos a construir conocimiento\u201d, diferentes profesionales del sector p\u00fablico, privado y consultores confiaron en esta nueva propuesta y experimentaron un dise\u00f1o educativo que fue m\u00e1s all\u00e1 de lo convencional. Para ello, una delicada selecci\u00f3n de profesionales expertos en temas de planes de cierre y planes de abandono fueron congregados para ofrecer un diplomado de alta calidad que agregue valor a las competencias de los profesionales participantes.<\/p>\n<p style=\"text-align: justify;\">Fuimos ambiciosos en trazar un objetivo retador en donde los participantes adquirieran conocimiento e informaci\u00f3n sobre aspectos t\u00e9cnicos, ambientales, sociales y econ\u00f3micos relacionados a la planificaci\u00f3n del cierre, con la finalidad de mirar estrat\u00e9gicamente la gesti\u00f3n de cierre de sus proyectos, apoyarse de informaci\u00f3n relevante sobre experiencias existentes y proponer a sus empresas oportunidades de mejora reales, creativas e innovadoras para realizar un cierre eficiente, de bajo costo y orientado a la sostenibilidad de sus negocios.<\/p>\n<p style=\"text-align: justify;\">Apoyados en herramientas de pensamiento creativo como el <em>design thinking<\/em>, el <em>cardsorting<\/em> y teor\u00eda de pensamiento lateral, se construyeron propuestas innovadoras que impactar\u00e1n significativamente en la manera m\u00e1s eficiente de proponer el cierre de proyectos, d\u00e1ndole <a href=\"https:\/\/gerens.pe\/blog\/el-verdadero-valor-de-un-plan-de-cierre-de-minas\/\" target=\"_blank\" rel=\"noopener\">valor <\/a>significativo a los componentes ambientales y sociales en el marco de la responsabilidad social corporativa de la empresas.<\/p>\n<p style=\"text-align: justify;\">Con mucho entusiasmo cubrimos las expectativas que nos propusimos, 1) los profesionales participantes podr\u00e1n aplicar la informaci\u00f3n y conocimiento relevante para contribuir en el desarrollo de una cultura donde los planes de cierre tengan importancia de car\u00e1cter estrat\u00e9gico, tambi\u00e9n 2) podr\u00e1n maximizar los impactos ambientales positivos, as\u00ed como la gesti\u00f3n social del cierre del proyecto, mejorando significativamente la imagen y la reputaci\u00f3n de la empresa y finalmente, 3) podr\u00e1n optimizar las garant\u00edas financieras asociadas al cierre, con una mejor estimaci\u00f3n de costos, un an\u00e1lisis amplio de las alternativas de cierre, reduciendo la incertidumbre asociada a este tipo de proyecto.<\/p>\n<p style=\"text-align: justify;\">Para terminar, extiendo una invitaci\u00f3n especial a los profesionales que quieran sumarse a esta experiencia sin precedentes en el mercado nacional, donde aseguramos un espacio de aprendizaje colaborativo, din\u00e1mico, de construcci\u00f3n constante de conocimiento y que les ofrece una distinci\u00f3n especial a los profesionales que satisfactoriamente concluyan con el programa. El impacto generado en la empresa frente a la comunidad y el estado, m\u00e1s que positivo, generar\u00e1 una nueva sensaci\u00f3n de confianza, algo en que creer, algo de que apoyarse para sostener relaci\u00f3n arm\u00f3nica con el entorno durante el desarrollo de los proyectos y en definitiva entender que el cierre de un proyecto m\u00e1s que un cierre es una oportunidad que aprovechar.<\/p>\n<p style=\"text-align: justify;\"><strong><em>La Escuela de Postgrado <a href=\"https:\/\/gerens.pe\/\">GERENS<\/a> ofrece el <a href=\"https:\/\/gerens.pe\/educacion-ejecutiva\/gestion-integral-de-planes-de-cierre-sector-minero-y-afines\/\" target=\"_blank\" rel=\"noopener\">programa en\u00a0Gesti\u00f3n Integral de Planes de Cierre &#8211; Sector Minero y Afines<\/a><\/em><\/strong><strong><em>, que lo preparar\u00e1 para abordar con una mirada estrat\u00e9gica los\u00a0aspectos t\u00e9cnicos, ambientales, sociales y econ\u00f3micos relacionados a la planificaci\u00f3n del cierre. Si tiene alguna pregunta, escr\u00edbanos al <a href=\"https:\/\/gerens.pe\/contacto\/\">formulario de contacto<\/a>.<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Innovador, atrevido, de alto impacto y de gran utilidad result\u00f3 la iniciativa de brindar a la \u201cacademia\u201d una oferta educativa diferente relacionada&#8230;<\/p>\n","protected":false},"author":21,"featured_media":3014,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49],"tags":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/gerens.pe\/blog\/wp-json\/wp\/v2\/posts\/3012"}],"collection":[{"href":"https:\/\/gerens.pe\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gerens.pe\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gerens.pe\/blog\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/gerens.pe\/blog\/wp-json\/wp\/v2\/comments?post=3012"}],"version-history":[{"count":0,"href":"https:\/\/gerens.pe\/blog\/wp-json\/wp\/v2\/posts\/3012\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gerens.pe\/blog\/wp-json\/wp\/v2\/media\/3014"}],"wp:attachment":[{"href":"https:\/\/gerens.pe\/blog\/wp-json\/wp\/v2\/media?parent=3012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gerens.pe\/blog\/wp-json\/wp\/v2\/categories?post=3012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gerens.pe\/blog\/wp-json\/wp\/v2\/tags?post=3012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}