{"id":2787,"date":"2017-04-12T16:48:06","date_gmt":"2017-04-12T21:48:06","guid":{"rendered":"https:\/\/gerens.pe\/blog\/?p=2787"},"modified":"2021-12-01T04:03:27","modified_gmt":"2021-12-01T04:03:27","slug":"habilidades-directivas-buen-ceo","status":"publish","type":"post","link":"https:\/\/gerens.pe\/blog\/habilidades-directivas-buen-ceo\/","title":{"rendered":"Habilidades directivas que se necesitan para ser un buen CEO"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2890 aligncenter\" src=\"https:\/\/gerens.pe\/blog\/wp-content\/uploads\/2017\/04\/Habilidades-directivas-necesita-CEO.jpg\" alt=\"https:\/\/gerens.pe\/blog\/wp-content\/uploads\/2017\/04\/Habilidades-directivas-necesita-CEO\" width=\"727\" height=\"417\" srcset=\"https:\/\/gerens.pe\/blog\/wp-content\/uploads\/2017\/04\/Habilidades-directivas-necesita-CEO.jpg 445w, https:\/\/gerens.pe\/blog\/wp-content\/uploads\/2017\/04\/Habilidades-directivas-necesita-CEO-300x172.jpg 300w, https:\/\/gerens.pe\/blog\/wp-content\/uploads\/2017\/04\/Habilidades-directivas-necesita-CEO-360x206.jpg 360w\" sizes=\"(max-width: 727px) 100vw, 727px\" \/><\/p>\n<p style=\"text-align: justify;\">M\u00e1s all\u00e1 que una persona sea due\u00f1o de su propio negocio o dirija una gran organizaci\u00f3n que forme parte de los Fortune 500, sus logros como gerente o CEO depender\u00e1n completamente de su habilidad efectiva de liderazgo. Sin excepci\u00f3n, el enfoque de liderazgo de un gerente debe impactar el desempe\u00f1o de su equipo y los resultados. De hecho, un estudio reciente de\u00a0<em>The Gallup Organization<\/em>\u00a0revel\u00f3 que el \u00fanico factor m\u00e1s importante en la productividad era la participaci\u00f3n del trabajador. El estudio a\u00f1adi\u00f3 que la falta de habilidad de liderazgo para crear y mantener la participaci\u00f3n de los trabajadores tiene como consecuencia la p\u00e9rdida de millones de d\u00f3lares anuales.<\/p>\n<p style=\"text-align: justify;\">Por tal motivo, la educaci\u00f3n ejecutiva\u00a0y el coaching son las industrias de mayor crecimiento que atienden a la comunidad empresarial. \u00a0A continuaci\u00f3n, algunas habilidades que comparten los l\u00edderes exitosos.<\/p>\n<h2 style=\"text-align: justify;\"><strong>Transparencia<\/strong><\/h2>\n<p style=\"text-align: justify;\">La transparencia consiste b\u00e1sicamente en la pr\u00e1ctica de honestidad dentro del lugar de trabajo. Es una se\u00f1al de integridad. Adem\u00e1s, los trabajadores responden positivamente a un CEO que est\u00e1 dispuesto a liderar con el ejemplo y adopta responsabilidades bajo los mismos est\u00e1ndares que establece en su equipo.<\/p>\n<h2 style=\"text-align: justify;\"><strong>Escucha activa<\/strong><\/h2>\n<p style=\"text-align: justify;\">Muchos de nosotros hemos pasado por la tortuosa experiencia de asistir a\u00a0un <em>focus group<\/em>\u00a0de trabajadores o completar\u00a0encuestas dif\u00edciles a fin de mejorar la cultura organizacional, solo para descubrir que la empresa no toma acci\u00f3n. \u00a0Es crucial que el gerente solicite las sugerencias de sus trabajadores para mejorar la moral y las condiciones de trabajo, pero es m\u00e1s importante, que act\u00fae a tiempo sobre esos problemas. Esto no quiere decir que el gerente pondr\u00e1 en pr\u00e1ctica todas las sugerencias, sino que formalmente abordar\u00e1 los inconvenientes y har\u00e1 saber a sus trabajadores lo que puede hacer. De lo contrario, solo dirige la atenci\u00f3n al problema, mas no demuestra a su equipo alguna intenci\u00f3n por resolverla.<\/p>\n<h2 style=\"text-align: justify;\"><strong>Capacidad de comunicar el prop\u00f3sito y el significado<\/strong><\/h2>\n<p style=\"text-align: justify;\">Consiste en lograr que todo el equipo est\u00e9 cohesionado dispuesto a trabajar en las metas se\u00f1aladas. Para ello, el gerente ha de comunicar los objetivos de largo plazo evitando hablar en t\u00e9rminos gen\u00e9ricos. Los trabajadores deben comprender el panorama general y tambi\u00e9n entender espec\u00edficamente c\u00f3mo se llevar\u00e1 a cabo el plan y cu\u00e1l ser\u00e1 la funci\u00f3n de cada uno.<\/p>\n<h2 style=\"text-align: justify;\"><strong>Enfoque<\/strong><\/h2>\n<p style=\"text-align: justify;\">Para un CEO, es com\u00fan que los detalles le lleguen diariamente incluso antes de que tome su primera taza de caf\u00e9 del d\u00eda. Los grandes l\u00edderes son capaces de filtrar el ruido y pasar el 80% de su tiempo en tareas que impactan directamente en el objetivo expl\u00edcito que se ha determinado. Es f\u00e1cil que el gerente se distraiga con peque\u00f1as emergencias que considera son prioridad. Pero la realidad nos dice que son las grandes tareas las que determinar\u00e1n el rumbo que el gerente debe tomar.<\/p>\n<h2 style=\"text-align: justify;\"><strong>Delegaci\u00f3n<\/strong><\/h2>\n<p style=\"text-align: justify;\">La delegaci\u00f3n no es solo una necesidad log\u00edstica, sino tambi\u00e9n una forma inigualable de mostrar respeto. Un gerente que no conf\u00eda en el buen desempe\u00f1o de su personal, genera desgaste emocional en ellos, sin mencionar una tensi\u00f3n palpable en el ambiente de trabajo\u00a0que al final tiene como resultado una p\u00e9rdida total de la responsabilidad personal. En lugar de asumir que su equipo no puede, \u00bfpor qu\u00e9 no demostrarle que cree en ellos?<\/p>\n<p style=\"text-align: justify;\">Cuando un gerente otorga responsabilidades a su equipo, demuestra lo mucho que cree en la\u00a0 capacidad de ellos para alcanzar el \u00e9xito en sus funciones.<\/p>\n<p style=\"text-align: justify;\">En complemento a las caracter\u00edsticas de liderazgo, estas habilidades ayudar\u00e1n a un gerente a mejorar su experiencia y efectividad, y con suerte, maximizar la satisfacci\u00f3n de los trabajadores de su organizaci\u00f3n. \u00a0Con un equipo y mentalidad adecuada, alcanzar un pr\u00f3spero negocio no estar\u00e1 fuera de alcance.<\/p>\n<p style=\"text-align: justify;\"><strong>Art\u00edculo traducido y adaptado de <a href=\"http:\/\/www.theglobaldispatch.com\/what-important-leadership-skills-help-to-make-a-great-ceo-89849\/\">The Global Dispatch\u00a0<\/a><\/strong><\/p>\n<p><strong><em><a href=\"https:\/\/gerens.pe\/\">G\u011aRENS<\/a> ofrece el programa de <\/em><\/strong><strong><em>Desarrollo de Habilidades Directivas<\/em><\/strong><strong><em>\u00a0para obtener competencias personales y cultura emocional para generar valor. Si tiene alguna pregunta sobre este programa, escr\u00edbanos al\u00a0<\/em><\/strong><a href=\"https:\/\/gerens.pe\/contactanos\/\"><strong><em>formulario de contacto<\/em><\/strong><\/a><strong><em>.<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s all\u00e1 que una persona sea due\u00f1o de su propio negocio o dirija una gran organizaci\u00f3n que forme parte de los Fortune&#8230;<\/p>\n","protected":false},"author":4,"featured_media":2890,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[306,205,270],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/gerens.pe\/blog\/wp-json\/wp\/v2\/posts\/2787"}],"collection":[{"href":"https:\/\/gerens.pe\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gerens.pe\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gerens.pe\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/gerens.pe\/blog\/wp-json\/wp\/v2\/comments?post=2787"}],"version-history":[{"count":2,"href":"https:\/\/gerens.pe\/blog\/wp-json\/wp\/v2\/posts\/2787\/revisions"}],"predecessor-version":[{"id":6211,"href":"https:\/\/gerens.pe\/blog\/wp-json\/wp\/v2\/posts\/2787\/revisions\/6211"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gerens.pe\/blog\/wp-json\/wp\/v2\/media\/2890"}],"wp:attachment":[{"href":"https:\/\/gerens.pe\/blog\/wp-json\/wp\/v2\/media?parent=2787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gerens.pe\/blog\/wp-json\/wp\/v2\/categories?post=2787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gerens.pe\/blog\/wp-json\/wp\/v2\/tags?post=2787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}